{"id":11660,"date":"2020-11-13T09:45:46","date_gmt":"2020-11-13T09:45:46","guid":{"rendered":"https:\/\/urcsupport.com\/?post_type=faq&#038;p=11660"},"modified":"2020-11-13T09:45:48","modified_gmt":"2020-11-13T09:45:48","slug":"is-z-wave-remote-tempereature-sensor-work-with-the-thermostat","status":"publish","type":"faq","link":"https:\/\/urcsupport.com\/es\/faq\/is-z-wave-remote-tempereature-sensor-work-with-the-thermostat\/","title":{"rendered":"Is Z-wave remote tempereature sensor work with the thermostat ?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Yes, the TBZ500 supports external Z-wave temperature sensor.<\/p>\n","protected":false},"template":"","meta":{"_crdt_document":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false},"tags":[312,341,342],"class_list":["post-11660","faq","type-faq","status-publish","hentry","tag-ecolink","tag-tbz500","tag-thermostat"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/urcsupport.com\/es\/wp-json\/wp\/v2\/faq\/11660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urcsupport.com\/es\/wp-json\/wp\/v2\/faq"}],"about":[{"href":"https:\/\/urcsupport.com\/es\/wp-json\/wp\/v2\/types\/faq"}],"wp:attachment":[{"href":"https:\/\/urcsupport.com\/es\/wp-json\/wp\/v2\/media?parent=11660"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urcsupport.com\/es\/wp-json\/wp\/v2\/tags?post=11660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}